{"id":1146,"date":"2011-11-29T13:16:49","date_gmt":"2011-11-29T15:16:49","guid":{"rendered":"https:\/\/www.poli.usp.br\/noticias\/arquivo-de-noticias\/1146-professor-faical-massad-ganha-premio-professor-do-ano-de-2011.html"},"modified":"2018-09-09T21:22:59","modified_gmt":"2018-09-10T00:22:59","slug":"professor-faical-massad-ganha-premio-professor-do-ano-de-2011","status":"publish","type":"post","link":"https:\/\/www.poli.usp.br\/en\/noticias\/professor-faical-massad-ganha-premio-professor-do-ano-de-2011\/","title":{"rendered":"Professor Fai\u00e7al Massad ganha Pr\u00eamio Professor do Ano de 2011"},"content":{"rendered":"<p style=\"text-align: center;\"><em>Premia\u00e7\u00e3o oferecida pela Associa\u00e7\u00e3o de Engenheiros Polit\u00e9cnicos (AEP)<\/em><\/p>\n<p style=\"text-align: center;\"><em> valoriza professores de destaque na Escola Polit\u00e9cnica.<\/em><\/p>\n<p style=\"text-align: justify;\">A Associa\u00e7\u00e3o dos Engenheiros Polit\u00e9cnicos realizou, no dia 24 de novembro, uma homenagem ao professor doutor Fai\u00e7al Massad, professor titular da Escola Polit\u00e9cnica (Poli) da Universidade de S\u00e3o Paulo (USP), no Departamento de Engenharia de Estruturas e Geot\u00e9cnica (PEF). O professor Fai\u00e7al Massad possui gradua\u00e7\u00e3o em Engenharia Civil pela Universidade de S\u00e3o Paulo (1965), Master of Science pela Harvard University (1969), com alguns cursos no MIT (Massachusetts Institute Of Technology) (1969); Doutorado (1978) e Livre Doc\u00eancia (1985) pela. Tem experi\u00eancia na \u00e1rea de Engenharia Civil, com \u00eanfase em geot\u00e9cnica. Atua especificamente em obras de terra e enrocamento, funda\u00e7\u00f5es, escava\u00e7\u00f5es e mec\u00e2nica dos solos e recebeu diversos pr\u00eamios e t\u00edtulos de 1982 \u00e0 2011 na \u00e1rea de geot\u00e9cnica e mec\u00e2nica dos solos.<\/p>\n<p style=\"text-align: justify;\">Estiveram presentes o diretor da Escola Polit\u00e9cnica da Universidade de S\u00e3o Paulo (USP), professor Jos\u00e9 Roberto Cardoso, o vice-diretor, prof. Jos\u00e9 Roberto Castilho Piqueira, o engenheiro e presidente da Associa\u00e7\u00e3o dos Engenheiros Polit\u00e9cnicos (AEP), Kamal Mattar. Entre as autoridades presentes tamb\u00e9m estavam o Prof. Dr. Ivan Gilberto Sandoval Falleiros, diretor da Escola Polit\u00e9cnica entre 2006 e 2010 e atualmente professor titular, o Prof. Miguel Angel Buelta Martinez, professor titular do departamento PEF, o professor Dr. Vahan Agopyan, diretor da Escola Polit\u00e9cnica de 2002 a 2006 e atual Pr\u00f3-reitor de p\u00f3s-gradua\u00e7\u00e3o da USP.<\/p>\n<p style=\"text-align: justify;\">Durante a solenidade, o Prof. Paulo Teixeira da Cruz homenageou o professor Fai\u00e7al Massad. A apresenta\u00e7\u00e3o est\u00e1 dispon\u00edvel no link <a href=\"http:\/\/issuu.com\/ofitexto\/docs\/apresentacao-faical-massad\">http:\/\/issuu.com\/ofitexto\/docs\/apresentacao-faical-massad<\/a>.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Confira o discurso de agradecimento do prof. Fai\u00e7al Massad<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cMe sinto muito honrado pela escolha do meu nome como professor do ano de 2011. Por que ser professor? Uma primeira resposta foi dada recentemente na dor da trag\u00e9dia que se abateu sobre a professora Rosileide, que foi atingida por um aluno que depois se suicidou, um caso lament\u00e1vel. O seu companheiro assim se manifestou, conforme not\u00edcia veiculada pelo Estad\u00e3o, em 23 de setembro. \u2018Preocupado com as constantes reclama\u00e7\u00f5es da esposa sobre o ambiente na escola, Hayakawo vinha tentando convenc\u00ea-la a mudar de emprego. \u2018Mas professor s\u00f3 d\u00e1 aula no amor mesmo e ela ama dar aula.\u2019\u2019<\/p>\n<p style=\"text-align: justify;\">Uma segunda poss\u00edvel resposta, por que ser professor, no meu entender, \u00e9 para conhecer. Ao ensinar, ao transmitir conhecimento, o professor est\u00e1 aprendendo. Todos n\u00f3s que damos aula sabemos disso. O objeto de conhecimento em qualquer \u00e1rea \u00e9 inesgot\u00e1vel. Em certa ocasi\u00e3o, perguntaram-me se n\u00e3o me cansava de repetir ano ap\u00f3s ano, e j\u00e1 se foram 45 anos, os mesmos conceitos b\u00e1sicos, as mesmas teorias. Respondi que na vida todos n\u00f3s nos movemos em fun\u00e7\u00e3o das novidades. E para os crist\u00e3os, h\u00e1 aquelas belas palavras do evangelho, que at\u00e9 cantamos nas nossas igrejas, \u2018Fa\u00e7o novas todas as coisas\u2019, diz o senhor. Se Deus faz novas todas as coisas, \u00e9 isso que nos move. E os professores tem um privil\u00e9gio de estar sempre recebendo alunos novos, jovens, na maioria das vezes, \u00e1vidos por conhecimento, e \u00e9 isso no fundo o que nos move. \u00c9 fato que o ensino nos leva a percorrer caminhos j\u00e1 trilhados e a parar nas mesmas esta\u00e7\u00f5es como coisa inevit\u00e1vel, tal como fala o famoso fil\u00f3sofo alem\u00e3o Hegel, a prop\u00f3sito da aquisi\u00e7\u00e3o da cultura, que deve ser feita pelo indiv\u00edduo, apesar de ela j\u00e1 ser de posse geral. No entanto, tudo \u00e9 movimento, resultados obtidos em \u00e9pocas anteriores podem abrir novos horizontes. \u00c9 pensar o que j\u00e1 foi pensado em busca do impensado, e isto \u00e9 muito gratificante. No meu caso, tem dado muitos frutos, gerado pesquisas cujos resultados tem sido divulgados ao meio t\u00e9cnico extra alunos da universidade. Nesse contexto, eu gosto que os alunos se manifestem em aulas, mesmo com perguntas aparentemente bobas. A esse prop\u00f3sito eu sempre fa\u00e7o quest\u00e3o de lembrar as equipes de inspe\u00e7\u00e3o de barragens existentes, que est\u00e3o em opera\u00e7\u00e3o nos Estados Unidos &#8211; ali\u00e1s essa \u00e9 uma atividade essencial em qualquer sociedade desenvolvida, para evitar trag\u00e9dias. A essa atividade essencial s\u00e3o agregados jovens engenheiros com o objetivo de fazer perguntas bobas, essas perguntas podem dar o que pensar, romper paradigmas e v\u00edcios de especialistas. Ent\u00e3o de prop\u00f3sito eles colocam esses jovens engenheiros para fazer essas perguntas. Para encerrar, gostaria de dizer breves palavras de agradecimento. Em primeiro lugar aos meus pais, nascidos no L\u00edbano, mas brasileiros por ado\u00e7\u00e3o, que cedo colocaram os filhos para correr, apontando na dire\u00e7\u00e3o dos estudos. E n\u00f3s estamos correndo at\u00e9 hoje. Aos meus familiares, irm\u00e3s e irm\u00e3os, pelos constantes incentivos e apoio, em particular \u00e0 minha irm\u00e3 Deise, que por um tempo foi arrimo da nossa fam\u00edlia. Aos primos e primas, em particular \u00e0 minha prima, conselheira educacional da fam\u00edlia desde os tempos embrion\u00e1rios de Mar\u00edlia, nossa cidade natal. \u00c0 minha amada esposa Matilde, aos meus filhos Jos\u00e9 e Anselmo, que me ajudaram a ver os alunos com outros olhos. Aos meus professores, em quem busquei atalhos para buscar a verdade e os conhecimentos, permitiram-me subir em seus ombros para tentar enxergar mais longe. \u00c0 Escola Polit\u00e9cnica da USP, aqui representada pelo seu diretor, prof. Cardoso, vice-diretor, prof. Piqueira, e ex-diretores aqui presentes, por ter propiciado que eu praticasse a engenharia, atrav\u00e9s de consultorias a projetos e \u00e0 constru\u00e7\u00e3o de obras civis, condi\u00e7\u00e3o sinequanon para se ensinar engenharia. \u00c0 AEP, pela homenagem que agrade\u00e7o de cora\u00e7\u00e3o. Ao tomar conhecimento dela, n\u00e3o pude deixar de lembrar as palavras de Jesus Cristo sobre o servo in\u00fatil, em Lucas, cap\u00edtulo 17, vers\u00edculo 10. \u2018Assim tamb\u00e9m v\u00f3s, quando fizerdes tudo o que vos for mandado, dizei: Somos servos in\u00fateis, porque fizemos somente o que dev\u00edamos fazer.\u2019 Muito obrigado.\u201d<\/p>","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center;\"><em>Premia\u00e7\u00e3o oferecida pela Associa\u00e7\u00e3o de Engenheiros Polit\u00e9cnicos (AEP)<\/em><\/p>\n<p style=\"text-align: center;\"><em> valoriza professores de destaque na Escola Polit\u00e9cnica.<\/em><\/p>\n<p style=\"text-align: justify;\">A Associa\u00e7\u00e3o dos Engenheiros Polit\u00e9cnicos realizou, no dia 24 de novembro, uma homenagem ao professor doutor Fai\u00e7al Massad, professor titular da Escola Polit\u00e9cnica (Poli) da Universidade de S\u00e3o Paulo (USP), no Departamento de Engenharia de Estruturas e Geot\u00e9cnica (PEF). O professor Fai\u00e7al Massad possui gradua\u00e7\u00e3o em Engenharia Civil pela Universidade de S\u00e3o Paulo (1965), Master of Science pela Harvard University (1969), com alguns cursos no MIT (Massachusetts Institute Of Technology) (1969); Doutorado (1978) e Livre Doc\u00eancia (1985) pela. Tem experi\u00eancia na \u00e1rea de Engenharia Civil, com \u00eanfase em geot\u00e9cnica. Atua especificamente em obras de terra e enrocamento, funda\u00e7\u00f5es, escava\u00e7\u00f5es e mec\u00e2nica dos solos e recebeu diversos pr\u00eamios e t\u00edtulos de 1982 \u00e0 2011 na \u00e1rea de geot\u00e9cnica e mec\u00e2nica dos solos.<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"event_title":"","event_details":"","event_timezone":"","event_gmap":"","event_image":"","event_image_url":"","event_calendar_link":"","event_location":"","event_datetime_with_summary":"","event_datetime":"","event_date":"","event_time":"","event_date_type":"","event_rulesummary":"","event_ticket_rsvp":"","event_capacity":"","event_capacity_remaining":"","event_capacity_sold":"","event_sold_out":"","event_low_stock":"","event_ticket_count":"","event_ticket_summary":"","event_sales_start":"","event_sales_end":"","event_ticket_price_from":"","event_ticket_price_to":"","event_ticket_price_range":"","event_date_year":"","event_date_month":"","event_date_month_short":"","event_date_day":"","event_date_day_name":"","event_date_iso":"","event_rsvp_capacity":"","event_rsvp_remaining":"","event_rsvp_going":"","event_rsvp_full":"","footnotes":""},"categories":[13],"tags":[176,845,848,830,871,870,858],"coauthors":[],"class_list":["post-1146","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-arquivo-de-noticias","tag-faical-massad-65","tag-ivan-gilberto-sandoval-falleiros-11","tag-jose-roberto-castilho-piqueira-50","tag-miguel-angel-buelta-martinez-01","tag-paulo-teixeira-da-cruz-98","tag-vahan-agopyan-96"],"_links":{"self":[{"href":"https:\/\/www.poli.usp.br\/en\/wp-json\/wp\/v2\/posts\/1146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.poli.usp.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.poli.usp.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.poli.usp.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.poli.usp.br\/en\/wp-json\/wp\/v2\/comments?post=1146"}],"version-history":[{"count":1,"href":"https:\/\/www.poli.usp.br\/en\/wp-json\/wp\/v2\/posts\/1146\/revisions"}],"predecessor-version":[{"id":5222,"href":"https:\/\/www.poli.usp.br\/en\/wp-json\/wp\/v2\/posts\/1146\/revisions\/5222"}],"wp:attachment":[{"href":"https:\/\/www.poli.usp.br\/en\/wp-json\/wp\/v2\/media?parent=1146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.poli.usp.br\/en\/wp-json\/wp\/v2\/categories?post=1146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.poli.usp.br\/en\/wp-json\/wp\/v2\/tags?post=1146"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.poli.usp.br\/en\/wp-json\/wp\/v2\/coauthors?post=1146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}